{"id":237039,"date":"2022-03-29T20:00:00","date_gmt":"2022-03-29T17:00:00","guid":{"rendered":"https:\/\/themewp.inform.click\/?p=237039"},"modified":"2021-10-27T01:44:14","modified_gmt":"2021-10-26T22:44:14","slug":"comment-rendre-une-adresse-e-mail-cliquable-dans-wordpress","status":"publish","type":"post","link":"https:\/\/themewp.inform.click\/fr\/comment-rendre-une-adresse-e-mail-cliquable-dans-wordpress\/","title":{"rendered":"Comment rendre une adresse e-mail cliquable dans WordPress"},"content":{"rendered":"<p>Vous avez probablement d\u00e9j\u00e0 vu des adresses e-mail cliquables sur le Web comme celle-ci, <a href=\"mailto:fake@email.com\">fake@email.com<\/a>.<\/p>\n<p>Si vous cliquez sur cette adresse e-mail, le client de messagerie par d\u00e9faut de votre ordinateur s&rsquo;ouvrira. Alors, comment ajouter des liens comme celui-ci \u00e0 votre site WordPress ?<\/p>\n<p>Voici un moyen simple d&rsquo;ajouter des liens de courrier \u00e9lectronique aux articles et aux pages, ainsi que le code HTML que vous pouvez utiliser pour les menus et les widgets.<\/p>\n<h2>Comment cr\u00e9er Mailto: liens<\/h2>\n<p><strong>MISE \u00c0 JOUR :<\/strong> Regardez mon nouveau didacticiel vid\u00e9o pour apprendre \u00e0 ajouter des adresses e-mail cliquables dans le nouvel \u00e9diteur Gutenberg, ainsi que des menus et des widgets.<\/p>\n<div class=\"sds-iframe-wrapper fitvidsignore\" style=\"position:relative;padding-top:56.25%;max-width:100%;\"><iframe allowfullscreen style=\"position:absolute;top:0;left:0;width:100%;height:100%;\" src=\"\/\/www.youtube.com\/embed\/qunoDA84pGI\" frameborder=\"0\"><\/iframe><\/div>\n<p><a href=\"http:\/\/link.competethemes.com\/subscribe\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">Abonnez-vous aux th\u00e8mes de comp\u00e9tition sur Youtube<\/a><\/p>\n<p>HTML5 a introduit de nouveaux types de liens, notamment le lien de courrier \u00e9lectronique sp\u00e9cial ou le <a href=\"https:\/\/css-tricks.com\/snippets\/html\/mailto-links\/\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">lien Mailto<\/a>. WordPress vous aide \u00e0 lier automatiquement les adresses e-mail sans toucher au code HTML.<\/p>\n<p>Tout d&rsquo;abord, saisissez une adresse e-mail simple dans un article ou une page. Mettez ensuite en surbrillance le texte de l&rsquo;adresse e-mail et cliquez sur l&rsquo;ic\u00f4ne du lien dans l&rsquo;\u00e9diteur.<\/p>\n<p><a href=\"https:\/\/themewp.inform.click\/wp-content\/uploads\/2021\/10\/post-180989-616f5cfcbb91e.png\" data-rel=\"lightbox\"><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/themewp.inform.click\/wp-content\/uploads\/2021\/10\/post-180989-616f5cfcbb91e.png\" alt=\"Comment rendre une adresse e-mail cliquable dans WordPress\" ><\/a><\/p>\n<p>Vous pouvez \u00e9galement appuyer sur cmd+k (ctrl+k) pour utiliser le raccourci du lien.<\/p>\n<p>WordPress reconna\u00eetra l&rsquo;adresse e-mail et ins\u00e8rera automatiquement le lien Mailto correct pour vous.<\/p>\n<p>Appuyez simplement sur la touche Entr\u00e9e\/Retour pour ajouter le lien et le tour est jou\u00e9.<\/p>\n<h3>Comment fonctionnent les liens de messagerie<\/h3>\n<p>Lorsque vous cr\u00e9ez un lien vers un site Web, vous incluez \u00ab\u00a0http:\/\/\u00a0\u00bb au d\u00e9but. Tous les liens n\u00e9cessitent un protocole et \u00ab\u00a0http:\/\/\u00a0\u00bb est le protocole hypertexte que nous utilisons pour \u00e9tablir un lien vers des pages Web.<\/p>\n<p>Mailto est un protocole diff\u00e9rent. Il est utilis\u00e9 lors d&rsquo;un lien vers une adresse e-mail. En pratique, vous devez juste vous rappeler d&rsquo;utiliser &quot;mailto:&quot; au lieu de &quot;http:\/\/&quot; lors du lien vers une adresse e-mail.<\/p>\n<h3>Le lien Mailto HTML<\/h3>\n<p>Si vous ajoutez le lien \u00e0 un widget ou \u00e0 un menu, vous n&rsquo;aurez pas la cr\u00e9ation automatique de lien Mailto que vous obtenez dans l&rsquo;\u00e9diteur de publication.<\/p>\n<p>Voici \u00e0 quoi doit ressembler l&rsquo;URL lors de l&rsquo;ajout d&rsquo;un lien d&rsquo;adresse e-mail \u00e0 un menu.<\/p>\n<pre><code>mailto:fake@email.com<\/code><\/pre>\n<p>Et voici le HTML complet pour un lien Mailto.<\/p>\n<pre><code>&lt;a href=\"mailto:fake@email.com\"&gt;fake@email.com&lt;\/a&gt;<\/code><\/pre>\n<h2>Liens email avec WordPress<\/h2>\n<p>Dans cet article, vous avez appris comment ajouter des liens de courrier \u00e9lectronique \u00e0 n&rsquo;importe quelle partie de votre site avec WordPress en utilisant le lien HTML5 \u00ab\u00a0Mailto\u00a0\u00bb.<\/p>\n<p>Rendre les adresses e-mail cliquables peut permettre aux visiteurs de vous contacter plus facilement. Vous pouvez m\u00eame mettre \u00e0 jour les liens pour avoir une <a href=\"https:\/\/css-tricks.com\/snippets\/html\/mailto-links\/#article-header-id-1\" target=\"_blank\" rel=\"noopener nofollow\" class=\"external external_icon\">ligne d&rsquo;objet pr\u00e9-\u00e9crite<\/a>.<\/p>\n<p>Si vous avez des questions sur l&rsquo;ajout d&rsquo;adresses e-mail cliquables \u00e0 votre site, veuillez poster un commentaire ci-dessous.<\/p>\n<p><div id=\"PostUnique_PostSource\" style=\"padding-top: 50px\">Source d&rsquo;enregistrement:  <a target=\"_blank\" rel=\"noopener nofollow\" href=\"\/\/www.competethemes.com\" class=\"external external_icon\">www.competethemes.com<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous voulez rendre une adresse e-mail cliquable ? Voici un moyen simple d&rsquo;ajouter des liens de courrier \u00e9lectronique aux articles et aux pages, ainsi que le code HTML que vous pouvez utiliser pour les menus et les widgets.<\/p>\n","protected":false},"author":1,"featured_media":261610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[568],"tags":[844],"class_list":["post-237039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-bases-de-wordpress","tag-affiai-fr"],"_links":{"self":[{"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/posts\/237039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/comments?post=237039"}],"version-history":[{"count":0,"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/posts\/237039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/media\/261610"}],"wp:attachment":[{"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/media?parent=237039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/categories?post=237039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/themewp.inform.click\/fr\/wp-json\/wp\/v2\/tags?post=237039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}